{"id":50475,"date":"2025-07-20T18:19:39","date_gmt":"2025-07-20T16:19:39","guid":{"rendered":"https:\/\/casacumbia.com\/product\/grand-plateau-en-melamine-papaia\/"},"modified":"2025-09-21T15:15:40","modified_gmt":"2025-09-21T13:15:40","slug":"grand-plateau-en-melamine-papaia","status":"publish","type":"product","link":"https:\/\/casacumbia.com\/en\/produit\/grand-plateau-en-melamine-papaia\/","title":{"rendered":"Grand Plateau en M\u00e9lamine PAPAYE"},"content":{"rendered":"<p>Compos\u00e9 d&#8217;une assiette de pr\u00e9sentation, d&#8217;une assiette plate, d&#8217;une assiette \u00e0 dessert, d&#8217;un bol et de deux tailles de plateau, le Service Papaia est un service de table en m\u00e9lamine qui offrira une exp\u00e9rience \u00e0 la fois artistique et exotique, capturant l&#8217;essence de la tendance disruptive du Tropical Flair gr\u00e2ce \u00e0 la combinaison de motifs expressifs, de couleurs audacieuses et d&#8217;\u00e9l\u00e9ments tropicaux, r\u00e9sultant en une collection vibrante et pleine de personnalit\u00e9, enrichissant n&#8217;importe quelle table.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Compos\u00e9 d&#8217;une assiette de pr\u00e9sentation, d&#8217;une assiette plate, d&#8217;une assiette \u00e0 dessert, d&#8217;un bol et de deux tailles de plateau,<\/p>\n","protected":false},"featured_media":32408,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[282],"product_tag":[181,176,166],"class_list":{"0":"post-50475","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-planches","7":"product_tag-integre-pim","8":"product_tag-petites-dimensions","9":"product_tag-produits-en-ligne","11":"first","12":"instock","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/casacumbia.com\/en\/wp-json\/wp\/v2\/product\/50475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casacumbia.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/casacumbia.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/casacumbia.com\/en\/wp-json\/wp\/v2\/comments?post=50475"}],"version-history":[{"count":2,"href":"https:\/\/casacumbia.com\/en\/wp-json\/wp\/v2\/product\/50475\/revisions"}],"predecessor-version":[{"id":54380,"href":"https:\/\/casacumbia.com\/en\/wp-json\/wp\/v2\/product\/50475\/revisions\/54380"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casacumbia.com\/en\/wp-json\/wp\/v2\/media\/32408"}],"wp:attachment":[{"href":"https:\/\/casacumbia.com\/en\/wp-json\/wp\/v2\/media?parent=50475"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/casacumbia.com\/en\/wp-json\/wp\/v2\/product_brand?post=50475"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/casacumbia.com\/en\/wp-json\/wp\/v2\/product_cat?post=50475"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/casacumbia.com\/en\/wp-json\/wp\/v2\/product_tag?post=50475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}